{"id":46611,"date":"2026-08-31T09:00:45","date_gmt":"2026-08-31T14:00:45","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=46611"},"modified":"2026-08-31T08:54:17","modified_gmt":"2026-08-31T13:54:17","slug":"real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/","title":{"rendered":"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho"},"content":{"rendered":"<p>\ud83d\udd38 Los Merengues regresan a la cima de LaLiga con tres victorias y dos duelos consecutivos marcando cuatro goles.<\/p>\n<p>#DEPORTES | El Real Madrid cuenta sus tres partidos de esta temporada por victorias, sustentadas en el estado de gracia de Jude Bellingham y Kylian Mbapp\u00e9. La \u00faltima, 4-0 ante un M\u00e1laga que volvi\u00f3 al Santiago Bernab\u00e9u ocho a\u00f1os despu\u00e9s y lo hizo sin complejos, pero sin poder mantener m\u00e1s all\u00e1 de 19 minutos la ilusi\u00f3n de lograr un buen resultado.<\/p>\n<p>El Real Madrid solvent\u00f3 el partido en once minutos. Al ritmo de Jude Bellingham y Kylian Mbapp\u00e9. Como cuatro d\u00edas atr\u00e1s ante la Real Sociedad. Dos futbolistas que han iniciado la temporada a un ritmo diferente. Sin posibilidad ni necesidad de completar una pretemporada al uso, ya que ambos se incorporaron en la fase final tras jugar un Mundial del que han conservado la inercia positiva.<\/p>\n<p>Bellingham vuelve a disfrutar sobre el c\u00e9sped. No lo hizo la pasada temporada. Mourinho parece haber encontrado su sitio. Aunque la confirmaci\u00f3n llegar\u00e1 en d\u00edas grandes, de momento, el segundo proyecto de Mou\u00a0en el Real Madrid camina con paso firme.<\/p>\n<p>Y Bellingham lo hace con exuberancia, agilidad y aplomo. Un f\u00edsico privilegiado para el futbol que vuelve a estar engrasado. Su primer gol lo demuestra. Cogi\u00f3 un bal\u00f3n suelto tras una arrancada de Kylian Mbapp\u00e9 y el que arranc\u00f3 fue el ingl\u00e9s, dejando atr\u00e1s a los defensas -el M\u00e1laga pidi\u00f3 falta en el inicio despu\u00e9s de que Jude impactase con la mano izquierda sobre el cuello de \u00c1ngel Recio- hasta llegar al \u00e1rea y cruzar el bal\u00f3n ante Alfonso Herrero.<\/p>\n<p>Minuto 19 y el Real Madrid abri\u00f3 la veda de una goleada fraguada a pesar de la valent\u00eda visitante. En su vuelta al Santiago Bernab\u00e9u ocho a\u00f1os despu\u00e9s y tras descender a la tercera categor\u00eda del futbol espa\u00f1ol, los de Juanfran Funes no perdieron su esencia. Salida de bal\u00f3n con riesgo y atrevimiento desde su propia \u00e1rea y verticalidad en campo rival, pero justo en esta zona les cost\u00f3 encontrar continuidad. En Primera Divisi\u00f3n y en el Santiago Bernab\u00e9u, estos pases suben de complejidad.<\/p>\n<p>Tampoco estuvo la suerte de su lado, aunque fue un condicionante mejor. El segundo gol lo provoc\u00f3 Bellingham con un remate de cabeza que despej\u00f3 Carlos Puga sobre la l\u00ednea, el bal\u00f3n toc\u00f3 en la espalda de Alfonso Herrero y se col\u00f3 en su porter\u00eda.<\/p>\n<p>El tercer tanto en once minutos fue obra de Kylian Mbapp\u00e9. Fiel a su cita con el gol remat\u00f3 de primeras un centro tenso de Trent Alexander-Arnold, ponderando con su buen pie la rotaci\u00f3n en los laterales de Mourinho.<\/p>\n<p>Y la del resto del equipo. Cinco cambios de inicio tras repetir once titular en los dos primeros encuentros, y el Real Madrid incluso subi\u00f3 el tono mostrado el mi\u00e9rcoles ante la Real Sociedad. De los pitos al descanso con el 1-1 el mi\u00e9rcoles a una segunda mitad sin historia este domingo.<\/p>\n<p>El Real Madrid baj\u00f3 el ritmo y no asumi\u00f3 riesgos con un marcador favorable ante el que Vin\u00edcius Junior fue el m\u00e1s incisivo, sin \u00e9xito, de intentar encontrar su gol. Eso s\u00ed, sum\u00f3 una asistencia a sus estad\u00edsticas tras una pared con Arda G\u00fcler que complet\u00f3 la goleada en el minuto 91.<\/p>\n<p>Antes, minutos para Yan Diomande, quien sali\u00f3 al terreno de juego en el minuto 64 y dej\u00f3 un arrancada por banda derecha y poco m\u00e1s, a\u00fan en un proceso espec\u00edfico de puesta a punto tras una pretemporada marcada por su futuro, hasta que se concret\u00f3 su llegada al Real Madrid adelant\u00e1ndose a clubes como Liverpool y Par\u00eds Saint-Germain.<\/p>\n<p>Segunda parte en la que el M\u00e1laga vio cerca su opci\u00f3n de marcar un tanto que, eso s\u00ed, no hubiera influido en el resultado final. Sin embargo, el penalti se\u00f1alado por el colegiado Juan Mart\u00ednez, quien vio mano de Diomande tras un rechace de Antonio R\u00fcdiger, fue revisado en el VAR y el propio \u00e1rbitro rectific\u00f3 su decisi\u00f3n tras ver la acci\u00f3n repetida en el monitor.<\/p>\n<p>4-0 para el Real Madrid y tres puntos para mantener su paso firme en el inicio de Liga, mientras que el M\u00e1laga sum\u00f3 su segunda derrota en su vuelta a la \u00e9lite, tras la cosechada en el campo del Atl\u00e9tico de Madrid, y acumula un punto tras tres partidos, con su empate frente al Deportivo A Coru\u00f1a.<\/p>\n<p>#Deportes #Futbol #RealMadrid #Golea #M\u00e1laga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 Los Merengues regresan a la cima de LaLiga con tres victorias y dos duelos consecutivos marcando cuatro<\/p>\n","protected":false},"author":1,"featured_media":46613,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-46611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38 Los Merengues regresan a la cima de LaLiga con tres victorias y dos duelos consecutivos marcando cuatro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-31T14:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1035\" \/>\n\t<meta property=\"og:image:height\" content=\"583\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho\",\"datePublished\":\"2026-08-31T14:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/\"},\"wordCount\":784,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/\",\"name\":\"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg\",\"datePublished\":\"2026-08-31T14:00:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg\",\"width\":1035,\"height\":583},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/31\\\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/","og_locale":"es_ES","og_type":"article","og_title":"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38 Los Merengues regresan a la cima de LaLiga con tres victorias y dos duelos consecutivos marcando cuatro","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-08-31T14:00:45+00:00","og_image":[{"width":1035,"height":583,"url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho","datePublished":"2026-08-31T14:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/"},"wordCount":784,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg","articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/","name":"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg","datePublished":"2026-08-31T14:00:45+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-31-at-08.26.06.jpeg","width":1035,"height":583},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/31\/real-madrid-propina-goleada-al-malaga-de-la-mano-de-mourinho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Real Madrid propina goleada al M\u00e1laga de la mano de Mourinho"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=46611"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46611\/revisions"}],"predecessor-version":[{"id":46612,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46611\/revisions\/46612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/46613"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=46611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=46611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=46611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}