{"id":46003,"date":"2026-08-12T12:09:49","date_gmt":"2026-08-12T17:09:49","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=46003"},"modified":"2026-08-12T12:09:59","modified_gmt":"2026-08-12T17:09:59","slug":"se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/","title":{"rendered":"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico"},"content":{"rendered":"<p>\ud83d\udd38El sistema se ubica a m\u00e1s de 4 mil 500 kil\u00f3metros de Canc\u00fan y se desplaza hacia el este, por lo que las autoridades descartan cualquier tipo de peligro para el territorio mexicano.<\/p>\n<p>#NACIONAL | La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil de Quintana Roo y la Comisi\u00f3n Nacional del Agua (Conagua) informaron sobre la formaci\u00f3n de la tormenta tropical \u00abCristobal\u00bb en aguas del Atl\u00e1ntico Norte.<\/p>\n<p>De acuerdo con los reportes oficiales emitidos a las 09:00 horas de este mi\u00e9rcoles 12 de agosto, el centro de la tormenta tropical se localiz\u00f3 a 1,420 kil\u00f3metros al oeste de las Azores y a aproximadamente 4,550 kil\u00f3metros al este-noreste de las costas de Canc\u00fan, Quintana Roo.<\/p>\n<p>Actualmente, el fen\u00f3meno meteorol\u00f3gico registra vientos m\u00e1ximos sostenidos de 75 km\/h, con rachas que alcanzan los 95 km\/h, y mantiene un desplazamiento acelerado hacia el este a una velocidad de 41 km\/h.<\/p>\n<p>Debido a su lejana ubicaci\u00f3n geogr\u00e1fica y a su trayectoria con rumbo alejado del continente americano, las autoridades enfatizaron que el sistema no representa ning\u00fan peligro para las costas de Quintana Roo ni para el resto del pa\u00eds.<\/p>\n<p>No obstante, las dependencias oficiales exhortan a la ciudadan\u00eda a mantenerse atenta a los avisos meteorol\u00f3gicos e informarse exclusivamente a trav\u00e9s de los canales institucionales de la Conagua y Protecci\u00f3n Civil Estatal para evitar desinformaci\u00f3n durante la presente temporada de ciclones tropicales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38El sistema se ubica a m\u00e1s de 4 mil 500 kil\u00f3metros de Canc\u00fan y se desplaza hacia el<\/p>\n","protected":false},"author":1,"featured_media":46005,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-46003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38El sistema se ubica a m\u00e1s de 4 mil 500 kil\u00f3metros de Canc\u00fan y se desplaza hacia el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-12T17:09:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T17:09:59+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico\",\"datePublished\":\"2026-08-12T17:09:49+00:00\",\"dateModified\":\"2026-08-12T17:09:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg\",\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/\",\"name\":\"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg\",\"datePublished\":\"2026-08-12T17:09:49+00:00\",\"dateModified\":\"2026-08-12T17:09:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg\",\"width\":590,\"height\":447},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38El sistema se ubica a m\u00e1s de 4 mil 500 kil\u00f3metros de Canc\u00fan y se desplaza hacia el","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-08-12T17:09:49+00:00","article_modified_time":"2026-08-12T17:09:59+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico","datePublished":"2026-08-12T17:09:49+00:00","dateModified":"2026-08-12T17:09:59+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg","articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/","name":"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg","datePublished":"2026-08-12T17:09:49+00:00","dateModified":"2026-08-12T17:09:59+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.30.51-1.jpeg","width":590,"height":447},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/se-forma-la-tormenta-tropical-cristobal-en-el-atlantico-norte-no-representa-riesgo-para-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Se forma la Tormenta Tropical Cristobal en el Atl\u00e1ntico Norte; no representa riesgo para M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=46003"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46003\/revisions"}],"predecessor-version":[{"id":46004,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46003\/revisions\/46004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/46005"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=46003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=46003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=46003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}