{"id":46000,"date":"2026-08-12T11:00:04","date_gmt":"2026-08-12T16:00:04","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=46000"},"modified":"2026-08-12T12:08:48","modified_gmt":"2026-08-12T17:08:48","slug":"atletas-recibiran-estimulo-economico-por-cada-medalla-ganada","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/","title":{"rendered":"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada"},"content":{"rendered":"<p>\ud83d\udd38La Conade reconocer\u00e1 econ\u00f3micamente cada presea conseguida por los deportistas mexicanos, incluidos sus entrenadores, tras su participaci\u00f3n internacional<\/p>\n<p>#DEPORTES |Los atletas mexicanos que conquisten medallas en competencias internacionales recibir\u00e1n un est\u00edmulo econ\u00f3mico por cada presea obtenida, anunci\u00f3 este mi\u00e9rcoles Rommel Pacheco, titular de la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (Conade).<\/p>\n<p>El funcionario explic\u00f3 durante la conferencia de prensa de la presidenta Claudia Sheinbaum que el esquema cambiar\u00e1, pues anteriormente se contemplaba premiar, en t\u00e9rminos generales, \u00fanicamente la medalla de mayor valor conseguida por cada deportista.<\/p>\n<p>Ahora, la disposici\u00f3n establece que todas las preseas obtenidas ser\u00e1n consideradas para otorgar los apoyos econ\u00f3micos. La medida tambi\u00e9n beneficiar\u00e1 a los entrenadores de los deportistas medallistas.<\/p>\n<p>Pacheco detall\u00f3 que los est\u00edmulos estar\u00e1n relacionados con las medallas y los resultados alcanzados, as\u00ed como con el nivel de la competencia en la que participen los deportistas.<\/p>\n<p>La decisi\u00f3n se da despu\u00e9s de la participaci\u00f3n de M\u00e9xico en los Juegos Centroamericanos y del Caribe 2026, celebrados en Santo Domingo, Rep\u00fablica Dominicana, donde la delegaci\u00f3n nacional estuvo integrada por 646 atletas.<\/p>\n<p>Adem\u00e1s de los premios por medalla, la Conade mantiene un esquema de becas para deportistas, cuyo monto m\u00e1s alto alcanza los 55 mil pesos mensuales, dependiendo de los resultados y criterios establecidos. Los atletas tambi\u00e9n pueden acceder a servicios de apoyo para su preparaci\u00f3n, como atenci\u00f3n m\u00e9dica y fisioterapia.<\/p>\n<p>El anuncio representa un cambio en la pol\u00edtica de est\u00edmulos al deporte de alto rendimiento, al establecer que los resultados de los atletas sean reconocidos econ\u00f3micamente por cada presea conseguida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38La Conade reconocer\u00e1 econ\u00f3micamente cada presea conseguida por los deportistas mexicanos, incluidos sus entrenadores, tras su participaci\u00f3n internacional<\/p>\n","protected":false},"author":1,"featured_media":46002,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-46000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38La Conade reconocer\u00e1 econ\u00f3micamente cada presea conseguida por los deportistas mexicanos, incluidos sus entrenadores, tras su participaci\u00f3n internacional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-12T16:00:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T17:08:48+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada\",\"datePublished\":\"2026-08-12T16:00:04+00:00\",\"dateModified\":\"2026-08-12T17:08:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/\",\"name\":\"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg\",\"datePublished\":\"2026-08-12T16:00:04+00:00\",\"dateModified\":\"2026-08-12T17:08:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg\",\"width\":813,\"height\":542},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/","og_locale":"es_ES","og_type":"article","og_title":"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38La Conade reconocer\u00e1 econ\u00f3micamente cada presea conseguida por los deportistas mexicanos, incluidos sus entrenadores, tras su participaci\u00f3n internacional","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-08-12T16:00:04+00:00","article_modified_time":"2026-08-12T17:08:48+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada","datePublished":"2026-08-12T16:00:04+00:00","dateModified":"2026-08-12T17:08:48+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg","articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/","name":"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg","datePublished":"2026-08-12T16:00:04+00:00","dateModified":"2026-08-12T17:08:48+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-10.25.28.jpeg","width":813,"height":542},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/atletas-recibiran-estimulo-economico-por-cada-medalla-ganada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Atletas recibir\u00e1n est\u00edmulo econ\u00f3mico por cada medalla ganada"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=46000"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46000\/revisions"}],"predecessor-version":[{"id":46001,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/46000\/revisions\/46001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/46002"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=46000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=46000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=46000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}