{"id":45988,"date":"2026-08-12T07:00:26","date_gmt":"2026-08-12T12:00:26","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=45988"},"modified":"2026-08-12T12:01:43","modified_gmt":"2026-08-12T17:01:43","slug":"ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/","title":{"rendered":"Ceden la cancha y Mineros completa la barrida en canc\u00fan"},"content":{"rendered":"<p>\ud83d\udd38 La quinteta cancunense volvi\u00f3 a tropezar en casa y dej\u00f3 escapar la oportunidad de cerrar la serie con una victoria ante Zacatecas<\/p>\n<p>#DEPORTES | El Calor de Canc\u00fan no logr\u00f3 reaccionar a tiempo y termin\u00f3 cediendo nuevamente ante los Mineros de Zacatecas, que se impusieron 67-78 en el Poliforum Canc\u00fan para llevarse por completo la serie correspondiente a la Temporada 2026 de la Liga Caliente.Mx LNBP. La quinteta visitante construy\u00f3 su ventaja desde el segundo periodo y, pese a los intentos locales por acercarse en el marcador, mantuvo el control hasta el final.<\/p>\n<p>El conjunto zacatecano tom\u00f3 la iniciativa desde el arranque con Tavario Miller y Anyelo Cisneros como protagonistas, aunque Canc\u00fan consigui\u00f3 equilibrar las acciones al cierre del primer cuarto gracias a Jesse Zarzuela y Brevin Galloway, dejando el parcial 14-14. La historia cambi\u00f3 en el segundo periodo, cuando Romeao Ferguson y Cisneros volvieron a marcar diferencia para que Mineros llegara al descanso con ventaja de 28-36. Tras el medio tiempo, El Calor aument\u00f3 la intensidad con Edgaras Zelionis, Bruno Cingala-Matos y Will Ellis, pero Zacatecas respondi\u00f3 de manera colectiva y conserv\u00f3 una c\u00f3moda diferencia de 45-57.<\/p>\n<p>En el \u00faltimo cuarto, los locales buscaron darle la vuelta al encuentro y Galloway tom\u00f3 el protagonismo ofensivo, pero la reacci\u00f3n no alcanz\u00f3 para poner en riesgo el triunfo visitante. Daishon Smith encabez\u00f3 a Mineros con 20 puntos, seguido por Ferguson con 15 y Kayo Goncalves con 12; por El Calor, Galloway termin\u00f3 con 19 unidades, mientras Ellis aport\u00f3 11 y Zelionis nueve. Con la derrota, Canc\u00fan lleg\u00f3 a seis descalabros en la campa\u00f1a, mientras Zacatecas alcanz\u00f3 seis victorias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 La quinteta cancunense volvi\u00f3 a tropezar en casa y dej\u00f3 escapar la oportunidad de cerrar la serie<\/p>\n","protected":false},"author":1,"featured_media":45990,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-45988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ceden la cancha y Mineros completa la barrida en canc\u00fan - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ceden la cancha y Mineros completa la barrida en canc\u00fan - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38 La quinteta cancunense volvi\u00f3 a tropezar en casa y dej\u00f3 escapar la oportunidad de cerrar la serie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-12T12:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T17:01:43+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Ceden la cancha y Mineros completa la barrida en canc\u00fan\",\"datePublished\":\"2026-08-12T12:00:26+00:00\",\"dateModified\":\"2026-08-12T17:01:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/\",\"name\":\"Ceden la cancha y Mineros completa la barrida en canc\u00fan - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg\",\"datePublished\":\"2026-08-12T12:00:26+00:00\",\"dateModified\":\"2026-08-12T17:01:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/12\\\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ceden la cancha y Mineros completa la barrida en canc\u00fan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ceden la cancha y Mineros completa la barrida en canc\u00fan - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/","og_locale":"es_ES","og_type":"article","og_title":"Ceden la cancha y Mineros completa la barrida en canc\u00fan - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38 La quinteta cancunense volvi\u00f3 a tropezar en casa y dej\u00f3 escapar la oportunidad de cerrar la serie","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-08-12T12:00:26+00:00","article_modified_time":"2026-08-12T17:01:43+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Ceden la cancha y Mineros completa la barrida en canc\u00fan","datePublished":"2026-08-12T12:00:26+00:00","dateModified":"2026-08-12T17:01:43+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg","articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/","name":"Ceden la cancha y Mineros completa la barrida en canc\u00fan - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg","datePublished":"2026-08-12T12:00:26+00:00","dateModified":"2026-08-12T17:01:43+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-12-at-08.33.06.jpeg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/12\/ceden-la-cancha-y-mineros-completa-la-barrida-en-cancun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Ceden la cancha y Mineros completa la barrida en canc\u00fan"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=45988"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45988\/revisions"}],"predecessor-version":[{"id":45989,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45988\/revisions\/45989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/45990"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=45988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=45988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=45988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}