{"id":45935,"date":"2026-08-10T11:11:33","date_gmt":"2026-08-10T16:11:33","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=45935"},"modified":"2026-08-10T11:12:22","modified_gmt":"2026-08-10T16:12:22","slug":"dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/","title":{"rendered":"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso"},"content":{"rendered":"<p>\ud83d\udd38Cada 10 de agosto se conmemora y surgi\u00f3 en 1985 en Itag\u00fc\u00ed, Colombia, para promover el descanso, el ocio y la recreaci\u00f3n como parte de una vida equilibrada.<\/p>\n<p>Cada 10 de agosto se celebra el D\u00eda Mundial de la Pereza, una fecha que, lejos de promover la inactividad permanente, naci\u00f3 como una iniciativa cultural para reivindicar el derecho al descanso, al ocio y a la recreaci\u00f3n.<\/p>\n<p>El origen de esta peculiar celebraci\u00f3n se remonta a 1985, en el municipio de Itag\u00fc\u00ed, Antioquia, Colombia, donde gestores culturales, artistas y habitantes impulsaron la primera jornada como una forma de llamar la atenci\u00f3n sobre la necesidad de contar con mayores espacios para las actividades culturales y recreativas.<\/p>\n<p>La iniciativa tambi\u00e9n plante\u00f3 una reflexi\u00f3n sobre el equilibrio entre trabajo y descanso. Sus impulsores consideraron que, as\u00ed como existen fechas destinadas a reconocer el esfuerzo de los trabajadores, tambi\u00e9n deb\u00eda existir un espacio para destacar la importancia de detenerse, convivir y disfrutar del tiempo libre.<\/p>\n<p>Con el paso de los a\u00f1os, la celebraci\u00f3n se convirti\u00f3 en una tradici\u00f3n en Itag\u00fc\u00ed y comenz\u00f3 a adquirir mayor reconocimiento fuera de Colombia<\/p>\n<p>Las actividades suelen incluir personas en pijama, hamacas, almohadas y camas, adem\u00e1s de presentaciones art\u00edsticas y encuentros comunitarios.<\/p>\n<p>M\u00e1s all\u00e1 del sentido humor\u00edstico de la fecha, el D\u00eda Mundial de la Pereza busca recordar que *<br \/>\ndescansar tambi\u00e9n es parte de una vida saludable y equilibrada, especialmente en una sociedad donde las jornadas laborales y las responsabilidades cotidianas pueden dejar poco espacio para el ocio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38Cada 10 de agosto se conmemora y surgi\u00f3 en 1985 en Itag\u00fc\u00ed, Colombia, para promover el descanso, el<\/p>\n","protected":false},"author":1,"featured_media":45937,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-45935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38Cada 10 de agosto se conmemora y surgi\u00f3 en 1985 en Itag\u00fc\u00ed, Colombia, para promover el descanso, el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-10T16:11:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-10T16:12:22+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso\",\"datePublished\":\"2026-08-10T16:11:33+00:00\",\"dateModified\":\"2026-08-10T16:12:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg\",\"articleSection\":[\"Viral\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/\",\"name\":\"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg\",\"datePublished\":\"2026-08-10T16:11:33+00:00\",\"dateModified\":\"2026-08-10T16:12:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg\",\"width\":1408,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/08\\\/10\\\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38Cada 10 de agosto se conmemora y surgi\u00f3 en 1985 en Itag\u00fc\u00ed, Colombia, para promover el descanso, el","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-08-10T16:11:33+00:00","article_modified_time":"2026-08-10T16:12:22+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso","datePublished":"2026-08-10T16:11:33+00:00","dateModified":"2026-08-10T16:12:22+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg","articleSection":["Viral"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/","name":"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg","datePublished":"2026-08-10T16:11:33+00:00","dateModified":"2026-08-10T16:12:22+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-10-at-11.09.51.jpeg","width":1408,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/08\/10\/dia-mundial-de-la-pereza-una-celebracion-que-reivindica-el-derecho-al-descanso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Mundial de la Pereza: una celebraci\u00f3n que reivindica el derecho al descanso"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=45935"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45935\/revisions"}],"predecessor-version":[{"id":45936,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45935\/revisions\/45936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/45937"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=45935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=45935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=45935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}