{"id":45363,"date":"2026-07-22T12:00:03","date_gmt":"2026-07-22T17:00:03","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=45363"},"modified":"2026-07-22T11:46:09","modified_gmt":"2026-07-22T16:46:09","slug":"abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/","title":{"rendered":"Abogado de \u00abEl Mayo\u00bb asegura que EU no ha localizado bienes para cobrar decomiso millonario"},"content":{"rendered":"<p>\ud83d\udd38 La defensa de Ismael Zambada afirm\u00f3 que las autoridades estadounidenses no han encontrado propiedades a nombre del narcotraficante para hacer efectivo el decomiso de 15 mil millones de d\u00f3lares.<\/p>\n<p>#INTERNACIONAL | Frank P\u00e9rez, abogado de Ismael \u00abEl Mayo\u00bb Zambada, asegur\u00f3 que el Gobierno de Estados Unidos no ha localizado bienes o propiedades a nombre del cofundador del C\u00e1rtel de Sinaloa para hacer efectivo el decomiso de 15 mil millones de d\u00f3lares que le fue impuesto junto con la sentencia de cadena perpetua.<\/p>\n<p>En entrevista con el periodista \u00c1ngel Hern\u00e1ndez, de Milenio, el litigante sostuvo que el cobro de esa cantidad representa un reto para las autoridades estadounidenses, debido a que personas con el nivel de operaci\u00f3n de Zambada suelen evitar registrar su patrimonio de manera directa.<\/p>\n<p>Las declaraciones se producen despu\u00e9s de que un tribunal federal en Brooklyn conden\u00f3 a \u00abEl Mayo\u00bb a prisi\u00f3n de por vida y orden\u00f3 el decomiso de 15 mil millones de d\u00f3lares, una de las sanciones econ\u00f3micas m\u00e1s elevadas impuestas en un caso de narcotr\u00e1fico en Estados Unidos.<\/p>\n<p>De forma paralela, el secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, reconoci\u00f3 que tampoco se han encontrado propiedades registradas a nombre de Zambada en M\u00e9xico, aunque las autoridades han asegurado bienes y cuentas relacionadas con la estructura del C\u00e1rtel de Sinaloa.<\/p>\n<p>El Gobierno de M\u00e9xico, por su parte, analiza la posibilidad de reclamar una parte de los recursos que eventualmente sean recuperados por Estados Unidos, al considerar que fueron obtenidos mediante actividades il\u00edcitas que tambi\u00e9n afectaron al pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 La defensa de Ismael Zambada afirm\u00f3 que las autoridades estadounidenses no han encontrado propiedades a nombre del<\/p>\n","protected":false},"author":1,"featured_media":45365,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-45363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abogado de &quot;El Mayo&quot; asegura que EU no ha localizado bienes para cobrar decomiso millonario - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogado de &quot;El Mayo&quot; asegura que EU no ha localizado bienes para cobrar decomiso millonario - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38 La defensa de Ismael Zambada afirm\u00f3 que las autoridades estadounidenses no han encontrado propiedades a nombre del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-22T17:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Abogado de \u00abEl Mayo\u00bb asegura que EU no ha localizado bienes para cobrar decomiso millonario\",\"datePublished\":\"2026-07-22T17:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/\",\"name\":\"Abogado de \\\"El Mayo\\\" asegura que EU no ha localizado bienes para cobrar decomiso millonario - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg\",\"datePublished\":\"2026-07-22T17:00:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/22\\\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogado de \u00abEl Mayo\u00bb asegura que EU no ha localizado bienes para cobrar decomiso millonario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogado de \"El Mayo\" asegura que EU no ha localizado bienes para cobrar decomiso millonario - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/","og_locale":"es_ES","og_type":"article","og_title":"Abogado de \"El Mayo\" asegura que EU no ha localizado bienes para cobrar decomiso millonario - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38 La defensa de Ismael Zambada afirm\u00f3 que las autoridades estadounidenses no han encontrado propiedades a nombre del","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-07-22T17:00:03+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Abogado de \u00abEl Mayo\u00bb asegura que EU no ha localizado bienes para cobrar decomiso millonario","datePublished":"2026-07-22T17:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg","articleSection":["Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/","name":"Abogado de \"El Mayo\" asegura que EU no ha localizado bienes para cobrar decomiso millonario - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg","datePublished":"2026-07-22T17:00:03+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-22-at-10.54.27-1.jpeg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/22\/abogado-de-el-mayo-asegura-que-eu-no-ha-localizado-bienes-para-cobrar-decomiso-millonario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Abogado de \u00abEl Mayo\u00bb asegura que EU no ha localizado bienes para cobrar decomiso millonario"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=45363"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45363\/revisions"}],"predecessor-version":[{"id":45364,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45363\/revisions\/45364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/45365"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=45363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=45363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=45363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}