{"id":45300,"date":"2026-07-21T12:00:32","date_gmt":"2026-07-21T17:00:32","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=45300"},"modified":"2026-07-21T11:17:31","modified_gmt":"2026-07-21T16:17:31","slug":"aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/","title":{"rendered":"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora"},"content":{"rendered":"<p>El cargamento era transportado en un tractocami\u00f3n con destino a Tijuana; un hombre fue detenido durante el operativo encabezado por fuerzas federales.<\/p>\n<p>#SONORA | Autoridades federales aseguraron m\u00e1s de tres toneladas de metanfetamina que eran transportadas ocultas entre costales de alimento para ganado en un tractocami\u00f3n que circulaba por la carretera Sonoyta\u2013Puerto Pe\u00f1asco, en Sonora. Durante la acci\u00f3n tambi\u00e9n fue detenido el operador de la unidad.<\/p>\n<p>El decomiso fue resultado de un operativo conjunto en el que participaron elementos de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), la Fiscal\u00eda General de la Rep\u00fablica (FGR), la Secretar\u00eda de la Defensa Nacional, la Guardia Nacional y la Secretar\u00eda de Marina, como parte de las labores de inteligencia e investigaci\u00f3n contra el tr\u00e1fico de drogas.<\/p>\n<p>De acuerdo con las autoridades, en la inspecci\u00f3n del veh\u00edculo fueron localizados aproximadamente 3 mil 25 kilogramos de metanfetamina escondidos entre la carga de alimento para ganado. El tr\u00e1iler ten\u00eda como destino la ciudad de Tijuana, Baja California.<\/p>\n<p>El secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, inform\u00f3 que el aseguramiento representa millones de dosis de droga que no llegar\u00e1n a las calles y un fuerte impacto econ\u00f3mico para las organizaciones dedicadas al narcotr\u00e1fico.<\/p>\n<p>El conductor, un hombre de 45 a\u00f1os de edad, fue detenido y puesto a disposici\u00f3n del Ministerio P\u00fablico Federal, junto con el cargamento y el tractocami\u00f3n asegurados, para el desarrollo de las investigaciones correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cargamento era transportado en un tractocami\u00f3n con destino a Tijuana; un hombre fue detenido durante el operativo<\/p>\n","protected":false},"author":1,"featured_media":45302,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,42],"tags":[],"class_list":["post-45300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-sonora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"El cargamento era transportado en un tractocami\u00f3n con destino a Tijuana; un hombre fue detenido durante el operativo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-21T17:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora\",\"datePublished\":\"2026-07-21T17:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg\",\"articleSection\":[\"Nacional\",\"SONORA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/\",\"name\":\"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg\",\"datePublished\":\"2026-07-21T17:00:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg\",\"width\":1200,\"height\":740},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/21\\\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/","og_locale":"es_ES","og_type":"article","og_title":"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora - El Estatal de M\u00e9xico","og_description":"El cargamento era transportado en un tractocami\u00f3n con destino a Tijuana; un hombre fue detenido durante el operativo","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-07-21T17:00:32+00:00","og_image":[{"width":1200,"height":740,"url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora","datePublished":"2026-07-21T17:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg","articleSection":["Nacional","SONORA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/","name":"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg","datePublished":"2026-07-21T17:00:32+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-21-at-11.14.09.jpeg","width":1200,"height":740},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/21\/aseguran-mas-de-tres-toneladas-de-metanfetamina-ocultas-en-alimento-para-ganado-en-sonora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Aseguran m\u00e1s de tres toneladas de metanfetamina ocultas en alimento para ganado en Sonora"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=45300"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45300\/revisions"}],"predecessor-version":[{"id":45301,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/45300\/revisions\/45301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/45302"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=45300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=45300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=45300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}