{"id":44715,"date":"2026-07-01T09:00:16","date_gmt":"2026-07-01T14:00:16","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=44715"},"modified":"2026-07-01T11:45:38","modified_gmt":"2026-07-01T16:45:38","slug":"claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/","title":{"rendered":"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad"},"content":{"rendered":"<p>\ud83d\udd38 La mandataria explic\u00f3 que las plantas de luz partieron ayer en un avi\u00f3n con destino a Venezuela como parte del apoyo adicional solicitado por las autoridades de la rep\u00fablica bolivariana.<\/p>\n<p>#NACIONAL | La presidenta Claudia Sheinbaum Pardo anunci\u00f3 ayer el env\u00edo de siete plantas generadoras de electricidad a Venezuela para fortalecer la ayuda humanitaria brindada tras los sismos ocurridos la semana pasada en ese pa\u00eds sudamericano.<\/p>\n<p>En su conferencia de prensa diaria en Palacio Nacional, adelant\u00f3 asimismo que se prepara un buque de la Secretar\u00eda de Marina para trasladar v\u00edveres e insumos reunidos en centros de acopio.<\/p>\n<p>La mandataria explic\u00f3 que las plantas de luz partieron ayer en un avi\u00f3n con destino a Venezuela como parte del apoyo adicional solicitado por las autoridades de la rep\u00fablica bolivariana.<\/p>\n<p>Sheinbaum agreg\u00f3 que representantes del grupo encargado de coordinar la ayuda mexicana sostuvieron comunicaci\u00f3n con autoridades m\u00e9dicas y de protecci\u00f3n civil venezolanas con el fin de conocer las necesidades m\u00e1s urgentes y definir nuevas acciones de apoyo para poblaci\u00f3n afectada por los sismos.<\/p>\n<p>Agreg\u00f3 que el gobierno mexicano prepara el env\u00edo de un barco para transportar los v\u00edveres y otros insumos reunidos por diversas instituciones y organizaciones, incluida a la embajada de Venezuela en M\u00e9xico.<\/p>\n<p>En apoyo al pueblo venezolano El Colegio de M\u00e9xico habilitar\u00e1 por dos d\u00edas un centro de acopio, que se ubicar\u00e1 frente a la sala de estudiantado de esa casa de estudios. Hoy podr\u00e1n llevar v\u00edveres en un horario de 08:30 a 18 horas y ma\u00f1ana de 08:30 a 14.<\/p>\n<p>La instituci\u00f3n educativa aclar\u00f3 que lo recaudado en esos dos d\u00edas se llevar\u00e1 al centro de acopio de la Universidad Nacional Aut\u00f3noma de M\u00e9xico para su canalizaci\u00f3n.<\/p>\n<p>#ClaudiaSheinbaum #Anuncia #Env\u00edo #Venezuela #Siete #Plantas #Generadoras #Electricidad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 La mandataria explic\u00f3 que las plantas de luz partieron ayer en un avi\u00f3n con destino a Venezuela<\/p>\n","protected":false},"author":1,"featured_media":44717,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-44715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38 La mandataria explic\u00f3 que las plantas de luz partieron ayer en un avi\u00f3n con destino a Venezuela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-01T14:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T16:45:38+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad\",\"datePublished\":\"2026-07-01T14:00:16+00:00\",\"dateModified\":\"2026-07-01T16:45:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/\"},\"wordCount\":321,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg\",\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/\",\"name\":\"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg\",\"datePublished\":\"2026-07-01T14:00:16+00:00\",\"dateModified\":\"2026-07-01T16:45:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg\",\"width\":941,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/07\\\/01\\\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/","og_locale":"es_ES","og_type":"article","og_title":"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38 La mandataria explic\u00f3 que las plantas de luz partieron ayer en un avi\u00f3n con destino a Venezuela","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-07-01T14:00:16+00:00","article_modified_time":"2026-07-01T16:45:38+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad","datePublished":"2026-07-01T14:00:16+00:00","dateModified":"2026-07-01T16:45:38+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/"},"wordCount":321,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg","articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/","name":"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg","datePublished":"2026-07-01T14:00:16+00:00","dateModified":"2026-07-01T16:45:38+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-01-at-09.51.50.jpeg","width":941,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/07\/01\/claudia-sheinbaum-anuncia-el-envio-a-venezuela-de-siete-generadoras-de-electricidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Claudia Sheinbaum anuncia el env\u00edo a Venezuela de siete generadoras de electricidad"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=44715"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44715\/revisions"}],"predecessor-version":[{"id":44716,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44715\/revisions\/44716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/44717"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=44715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=44715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=44715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}