{"id":44493,"date":"2026-06-24T15:00:11","date_gmt":"2026-06-24T20:00:11","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=44493"},"modified":"2026-06-24T11:35:17","modified_gmt":"2026-06-24T16:35:17","slug":"tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/","title":{"rendered":"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria"},"content":{"rendered":"<p>\ud83d\udd38 Una amplia mayor\u00eda de los apostadores anticipan una victoria mexicana, mientras que 26% de estos ven que la selecci\u00f3n de Chequia dar\u00e1 la sorpresa.<\/p>\n<p>#MUNDIAL\u26bd\ue000 | La Selecci\u00f3n Mexicana de futbol vuelve a partir como favorita en los mercados de predicci\u00f3n, ya que datos de la plataforma Polymarket colocan al combinado nacional con 51 por ciento de posibilidades de llevarse la victoria frente a Chequia en el estadio Ciudad de M\u00e9xico.<\/p>\n<p>Una amplia mayor\u00eda de los apostadores anticipan una victoria para el Tricolor, mientras que 26 por ciento de estos ven que la selecci\u00f3n de Chequia dar\u00e1 la sorpresa en el partido de hoy llev\u00e1ndose los tres puntos.<\/p>\n<p>En una menor proporci\u00f3n, las predicciones del resultado apuntan a que 25 por ciento de las apuestas realizadas por los usuarios de la plataforma prev\u00e9n que se dividir\u00e1n puntos ambas selecciones, resultado que no mover\u00eda el panorama para la Selecci\u00f3n Mexicana.<\/p>\n<p>En otras plataformas, como es el caso de Kalshi, dan un mayor colch\u00f3n para M\u00e9xico, ya que en este sitio las apuestas hacia una victoria mexicana la noche de hoy se favorecen con 53 por ciento.<\/p>\n<p>Por otro lado, solo 25 por ciento pronostica una victoria de la selecci\u00f3n europea, que actualmente suma solo un punto en la competici\u00f3n y est\u00e1 obligada a ganarle al combinado nacional.<\/p>\n<p>De igual forma, en Manifold Markets se pronostica una victoria mexicana, con 53 por ciento de los pron\u00f3sticos de apuesta a su favor.<\/p>\n<p>Sobre las predicciones de qui\u00e9n se alzar\u00e1 con el m\u00e1ximo trofeo del f\u00fatbol, se tiene un margen mucho m\u00e1s apretado que en los partidos de fase de grupos del torneo, donde los datos de Polymarket muestran que 19 por ciento de las apuestas son a favor de Francia.<\/p>\n<p>En segunda posici\u00f3n se encuentra la selecci\u00f3n de Argentina, comandada por el m\u00e1ximo anotador de los mundiales, Lionel Messi, donde las apuestas de los usuarios de la plataforma le dan un porcentaje de posibilidad de ser campe\u00f3n del 15 por ciento.<\/p>\n<p>Mientras que en la tercera posici\u00f3n se encuentra Espa\u00f1a, que perdi\u00f3 terreno en las predicciones tras el empate sorpresivo con la selecci\u00f3n africana de Cabo Verde, donde ahora los apostadores le ven 14 por ciento de posibilidades de ser campeones.<\/p>\n<p>Polymarket muestra que para la Selecci\u00f3n Mexicana sus chances de ganar el trofeo mundial est\u00e1n muy lejos de concretarse, ya que solo 1 por ciento ve que M\u00e9xico gane su primer mundial.<\/p>\n<p>#Mundial2026 #Selecci\u00f3nMexicana #Tricolor #Favorito #Ante #Chequia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 Una amplia mayor\u00eda de los apostadores anticipan una victoria mexicana, mientras que 26% de estos ven que<\/p>\n","protected":false},"author":1,"featured_media":44495,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-44493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38 Una amplia mayor\u00eda de los apostadores anticipan una victoria mexicana, mientras que 26% de estos ven que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-24T20:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1033\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria\",\"datePublished\":\"2026-06-24T20:00:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/\",\"name\":\"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg\",\"datePublished\":\"2026-06-24T20:00:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg\",\"width\":1033,\"height\":582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/24\\\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/","og_locale":"es_ES","og_type":"article","og_title":"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38 Una amplia mayor\u00eda de los apostadores anticipan una victoria mexicana, mientras que 26% de estos ven que","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-06-24T20:00:11+00:00","og_image":[{"width":1033,"height":582,"url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria","datePublished":"2026-06-24T20:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg","articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/","name":"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg","datePublished":"2026-06-24T20:00:11+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-24-at-10.01.28.jpeg","width":1033,"height":582},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/24\/tricolor-favorito-ante-chequia-predicciones-le-otorgan-51-porciento-de-probabilidad-de-victoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Tricolor, favorito ante Chequia; predicciones le otorgan 51 porciento de probabilidad de victoria"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=44493"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44493\/revisions"}],"predecessor-version":[{"id":44494,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44493\/revisions\/44494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/44495"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=44493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=44493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=44493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}