{"id":44450,"date":"2026-06-17T11:00:14","date_gmt":"2026-06-17T16:00:14","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=44450"},"modified":"2026-06-24T01:51:35","modified_gmt":"2026-06-24T06:51:35","slug":"guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/","title":{"rendered":"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026"},"content":{"rendered":"<p>\ud83d\udd38 Los Juegos Centroamericanos y del Caribe Santo Domingo 2026 se realizar\u00e1n entre finales de julio y principios de agosto.<\/p>\n<p>#LE\u00d3N | Una delegaci\u00f3n de entre 30 y 35 atletas es la cifra que se proyecta represente a Guanajuato en los pr\u00f3ximos Juegos Centroamericanos y del Caribe Santo Domingo 2026. A la cabeza de la comitiva est\u00e1 Celia Pulido, quien busca arrasar en las pruebas de nataci\u00f3n.<\/p>\n<p>Rumbo a la justa regional, Guanajuato poco a poco va sumando deportistas que obtienen plazas para M\u00e9xico. Entre los atletas que se proyectan est\u00e1 la nadadora Celia Pulido, quien de manera simb\u00f3lica ha recibido las medallas que Liliana Ib\u00e1\u00f1ez logr\u00f3 en la edici\u00f3n de Barranquilla 2018, donde con nueve preseas fue la m\u00e1xima galardonada de M\u00e9xico.<\/p>\n<p>Pulido Ortiz, nadadora con experiencia en los Juegos Ol\u00edmpicos de Par\u00eds 2024, ahora toma el relevo para convertirse en la nueva figura de la nataci\u00f3n guanajuatense y mexicana. Para Santo Domingo 2026 se prev\u00e9 su participaci\u00f3n en por lo menos cinco pruebas, entre eventos individuales y relevos. Otros prospectos para la alberca son Omar Ruelas y Erick Ra\u00fal Villalpando.<\/p>\n<p>En boliche, disciplina que ha dado importantes resultados para la entidad, levantan la mano Dante Romero, Ricardo Lecuona e Iliana Lomel\u00ed. En tiro deportivo y sus diversas modalidades se proyecta a Luis Orranti, Goretti Zumaya y Carlos Adri\u00e1n Gonz\u00e1lez. Para conquistar y romper marcas en la pista, se tiene considerada a Laura Galv\u00e1n para la prueba de 21 kil\u00f3metros; adem\u00e1s figuran Ari\u00e1n Ch\u00eda, Mario Uriel L\u00f3pez, Luz Guadalupe Rocha, Sabrina Salcedo, Sebasti\u00e1n Torres y Ricardo Ortiz.<\/p>\n<p>Para el hockey sobre pasto, Guanajuato se ha consolidado como base de los selectivos nacionales de ambas ramas; por ello, entre los atletas a seguir se perfilan Alan Estrada, Alberto Rangel y Naomi Cardiel.<\/p>\n<p>En otras disciplinas se proyecta a Erick Barea para el baloncesto 3&#215;3, as\u00ed como a Gerardo Ulloa, Adair Guti\u00e9rrez y Montserrath Rodr\u00edguez en ciclismo de monta\u00f1a. Cabe resaltar que tambi\u00e9n se tiene en el radar la posibilidad de contar en judo con la medallista ol\u00edmpica Prisca Awiti. Asimismo, apunta a la justa regional el arquero Mat\u00edas Grande.<\/p>\n<p>En la justa regional, aunque la Ceremonia de Inauguraci\u00f3n est\u00e1 programada para el 24 de julio, las competencias deportivas comenzar\u00e1n desde el 20 de julio con el polo acu\u00e1tico, mientras que la clausura se realizar\u00e1 el ocho de agosto. Para esta edici\u00f3n se busca superar la cosecha obtenida en San Salvador 2023, donde Guanajuato aport\u00f3 37 medallas para M\u00e9xico: 15 de oro, 13 de plata y 9 de bronce.<\/p>\n<p>#Guanajuato #Proyecta #Delegaci\u00f3n #35Atletas #Para #SantoDomingo2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 Los Juegos Centroamericanos y del Caribe Santo Domingo 2026 se realizar\u00e1n entre finales de julio y principios<\/p>\n","protected":false},"author":1,"featured_media":44452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,35],"tags":[],"class_list":["post-44450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-guanajuato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026 - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026 - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38 Los Juegos Centroamericanos y del Caribe Santo Domingo 2026 se realizar\u00e1n entre finales de julio y principios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-17T16:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T06:51:35+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026\",\"datePublished\":\"2026-06-17T16:00:14+00:00\",\"dateModified\":\"2026-06-24T06:51:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/\"},\"wordCount\":454,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg\",\"articleSection\":[\"Deportes\",\"Guanajuato\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/\",\"name\":\"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026 - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg\",\"datePublished\":\"2026-06-17T16:00:14+00:00\",\"dateModified\":\"2026-06-24T06:51:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg\",\"width\":1090,\"height\":597},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/06\\\/17\\\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026 - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026 - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38 Los Juegos Centroamericanos y del Caribe Santo Domingo 2026 se realizar\u00e1n entre finales de julio y principios","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-06-17T16:00:14+00:00","article_modified_time":"2026-06-24T06:51:35+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026","datePublished":"2026-06-17T16:00:14+00:00","dateModified":"2026-06-24T06:51:35+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/"},"wordCount":454,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg","articleSection":["Deportes","Guanajuato"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/","name":"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026 - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg","datePublished":"2026-06-17T16:00:14+00:00","dateModified":"2026-06-24T06:51:35+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-17-at-11.08.24.jpeg","width":1090,"height":597},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/06\/17\/guanajuato-proyecta-una-delegacion-de-35-atletas-para-santo-domingo-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Guanajuato proyecta una delegaci\u00f3n de 35 atletas para Santo Domingo 2026"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=44450"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44450\/revisions"}],"predecessor-version":[{"id":44451,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/44450\/revisions\/44451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/44452"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=44450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=44450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=44450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}