{"id":43118,"date":"2026-05-13T11:17:10","date_gmt":"2026-05-13T16:17:10","guid":{"rendered":"https:\/\/elestataldemexico.com\/?p=43118"},"modified":"2026-05-13T11:17:10","modified_gmt":"2026-05-13T16:17:10","slug":"acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico","status":"publish","type":"post","link":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/","title":{"rendered":"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico"},"content":{"rendered":"<div class=\"morv3-section-header\">\n<div class=\"morv3-headingl-contenth\">\ud83d\udd38Se integr\u00f3 la Comisi\u00f3n de Modernizaci\u00f3n para dar seguimiento a los acuerdos con representantes del sector * El acuerdo contempla un ajuste responsable a la tarifa orientado al mejoramiento de unidades y del servicio al usuario<\/div>\n<\/div>\n<div class=\"morv3-prensa-text-container\">\n<div class=\"morv3-bodyl-contentl-justify w-richtext\">\n<p>#MORELOS | Para atender el rezago hist\u00f3rico del transporte p\u00fablico en Morelos y avanzar hacia un modelo de movilidad m\u00e1s eficiente y digno, el Gobierno del Estado alcanz\u00f3 acuerdos con el sector transportista para impulsar una estrategia integral de modernizaci\u00f3n del servicio.<\/p>\n<p>Como parte de este proceso, a partir del pr\u00f3ximo 01 de julio la tarifa base del transporte p\u00fablico tendr\u00e1 una actualizaci\u00f3n de 10 a 13 pesos. Este ajuste estar\u00e1 orientado a mejorar las condiciones del servicio, fortalecer la supervisi\u00f3n institucional y colocar a las y los usuarios en el centro de la pol\u00edtica de movilidad.<\/p>\n<p>\u201cLa modernizaci\u00f3n del transporte p\u00fablico debe ir de la mano del bienestar de las familias. Este acuerdo busca mejorar el servicio que reciben diariamente las y los ciudadanos, con unidades m\u00e1s dignas, mayor orden y una mejor atenci\u00f3n para las personas usuarias\u201d, expres\u00f3 la gobernadora Margarita Gonz\u00e1lez Saravia.<\/p>\n<p>Como eje rector de este proceso se integr\u00f3 la Comisi\u00f3n de Modernizaci\u00f3n conformada por la Secretar\u00eda de Econom\u00eda, la Secretar\u00eda de Administraci\u00f3n y Finanzas, la Coordinaci\u00f3n General de Movilidad y Transporte, la Oficina de la Gubernatura y la Agencia de Transformaci\u00f3n Digital, as\u00ed como dos representantes del sector por regi\u00f3n.<\/p>\n<p>La estrategia contempla la renovaci\u00f3n gradual del parque vehicular con respaldo institucional y financiero, as\u00ed como la incorporaci\u00f3n de tecnolog\u00eda mediante la instalaci\u00f3n de dispositivos de cobro digital en las unidades. Asimismo, se implementar\u00e1 capacitaci\u00f3n obligatoria para operadores con el objetivo de mejorar la calidad en la atenci\u00f3n que brindan.<\/p>\n<p>Tambi\u00e9n se impulsar\u00e1n acciones encaminadas a la electromovilidad y al fortalecimiento de modelos de transporte sustentable.<\/p>\n<p>Con estas medidas, el Gobierno del Estado busca que las y los ciudadanos cuenten con un transporte p\u00fablico m\u00e1s seguro, ordenado y digno, mediante acuerdos para mejorar el servicio, incorporar tecnolog\u00eda y garantizar una atenci\u00f3n m\u00e1s humana.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38Se integr\u00f3 la Comisi\u00f3n de Modernizaci\u00f3n para dar seguimiento a los acuerdos con representantes del sector * El<\/p>\n","protected":false},"author":1,"featured_media":43119,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,7],"tags":[],"class_list":["post-43118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morelos","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico - El Estatal de M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico - El Estatal de M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd38Se integr\u00f3 la Comisi\u00f3n de Modernizaci\u00f3n para dar seguimiento a los acuerdos con representantes del sector * El\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/\" \/>\n<meta property=\"og:site_name\" content=\"El Estatal de M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T16:17:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\"},\"headline\":\"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico\",\"datePublished\":\"2026-05-13T16:17:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg\",\"articleSection\":[\"Morelos\",\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/\",\"name\":\"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico - El Estatal de M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg\",\"datePublished\":\"2026-05-13T16:17:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg\",\"width\":2560,\"height\":1835},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/2026\\\/05\\\/13\\\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elestataldemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"name\":\"El Estatal de M\u00e9xico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elestataldemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#organization\",\"name\":\"El Estatal de M\u00e9xico\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"contentUrl\":\"https:\\\/\\\/elestataldemexico.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-elestatal.png\",\"width\":504,\"height\":97,\"caption\":\"El Estatal de M\u00e9xico\"},\"image\":{\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elestataldemexico.com\\\/#\\\/schema\\\/person\\\/6c7813c13d2c1571771f592f0fe866bb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/elestataldemexico.com\"],\"url\":\"https:\\\/\\\/elestataldemexico.com\\\/index.php\\\/author\\\/info_qk62m3p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico - El Estatal de M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/","og_locale":"es_ES","og_type":"article","og_title":"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico - El Estatal de M\u00e9xico","og_description":"\ud83d\udd38Se integr\u00f3 la Comisi\u00f3n de Modernizaci\u00f3n para dar seguimiento a los acuerdos con representantes del sector * El","og_url":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/","og_site_name":"El Estatal de M\u00e9xico","article_published_time":"2026-05-13T16:17:10+00:00","og_image":[{"width":2560,"height":1835,"url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#article","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/"},"author":{"name":"admin","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb"},"headline":"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico","datePublished":"2026-05-13T16:17:10+00:00","mainEntityOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg","articleSection":["Morelos","Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/","url":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/","name":"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico - El Estatal de M\u00e9xico","isPartOf":{"@id":"https:\/\/elestataldemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#primaryimage"},"image":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg","datePublished":"2026-05-13T16:17:10+00:00","breadcrumb":{"@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#primaryimage","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2026\/05\/6a03c87d628d3dba0714cf2b_WhatsApp-Image-2026-05-12-at-6.34.02-PM-scaled.jpeg","width":2560,"height":1835},{"@type":"BreadcrumbList","@id":"https:\/\/elestataldemexico.com\/index.php\/2026\/05\/13\/acuerdan-gobierno-del-estado-y-transportistas-modernizacion-del-transporte-publico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elestataldemexico.com\/"},{"@type":"ListItem","position":2,"name":"Acuerdan Gobierno del estado y transportistas modernizaci\u00f3n del transporte p\u00fablico"}]},{"@type":"WebSite","@id":"https:\/\/elestataldemexico.com\/#website","url":"https:\/\/elestataldemexico.com\/","name":"El Estatal de M\u00e9xico","description":"","publisher":{"@id":"https:\/\/elestataldemexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elestataldemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elestataldemexico.com\/#organization","name":"El Estatal de M\u00e9xico","url":"https:\/\/elestataldemexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","contentUrl":"https:\/\/elestataldemexico.com\/wp-content\/uploads\/2025\/05\/cropped-elestatal.png","width":504,"height":97,"caption":"El Estatal de M\u00e9xico"},"image":{"@id":"https:\/\/elestataldemexico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elestataldemexico.com\/#\/schema\/person\/6c7813c13d2c1571771f592f0fe866bb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5ed2db9923a3ad3c0a47f6b3aec7abcb43924b9322251ade16472fc06f7bb5b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/elestataldemexico.com"],"url":"https:\/\/elestataldemexico.com\/index.php\/author\/info_qk62m3p3\/"}]}},"_links":{"self":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/43118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=43118"}],"version-history":[{"count":1,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/43118\/revisions"}],"predecessor-version":[{"id":43120,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/posts\/43118\/revisions\/43120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media\/43119"}],"wp:attachment":[{"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=43118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=43118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elestataldemexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=43118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}